{"id":7076,"date":"2022-06-20T07:00:00","date_gmt":"2022-06-19T22:00:00","guid":{"rendered":"https:\/\/na-3.com\/wp_na-blog\/?p=7076"},"modified":"2022-09-23T22:36:32","modified_gmt":"2022-09-23T13:36:32","slug":"%e3%83%89%e3%83%ad%e3%83%bc%e3%83%b3%e3%81%ae%e6%a9%9f%e4%bd%93%e7%99%bb%e9%8c%b2%e7%be%a9%e5%8b%99%e9%96%8b%e5%a7%8b","status":"publish","type":"post","link":"https:\/\/na-3.com\/wp_na-blog\/2022\/06\/20\/%e3%83%89%e3%83%ad%e3%83%bc%e3%83%b3%e3%81%ae%e6%a9%9f%e4%bd%93%e7%99%bb%e9%8c%b2%e7%be%a9%e5%8b%99%e9%96%8b%e5%a7%8b\/","title":{"rendered":"\u30c9\u30ed\u30fc\u30f3\u306e\u6a5f\u4f53\u767b\u9332\u7fa9\u52d9\u958b\u59cb"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u30c9\u30ed\u30fc\u30f3\u306e\u6a5f\u4f53\u767b\u9332\u7fa9\u52d9\u5236\u5ea6\u304c\u672c\u65e5\uff12\uff10\u65e5\u304b\u3089\u59cb\u307e\u3063\u305f\u3002\uff11\uff10\uff10\u30b0\u30e9\u30e0\u4ee5\u4e0a\u304c\u5bfe\u8c61\u3067MAVIC MINI\u3082\u5bfe\u8c61\u3068\u306a\u308b\u3002\u4e8b\u6545\u3084\u30c8\u30e9\u30d6\u30eb\u306e\u969b\u3001\u6240\u6709\u8005\u3092\u901f\u3084\u304b\u306b\u7279\u5b9a\u3059\u308b\u72d9\u3044\u3002\u7121\u767b\u9332\u306e\u98db\u884c\u3092\u7981\u3058\u3001\u9055\u53cd\u8005\u306b\u306f\uff11\u5e74\u4ee5\u4e0b\u306e\u61f2\u5f79\u304b\uff15\uff10\u4e07\u5186\u4ee5\u4e0b\u306e\u7f70\u91d1\u3092\u79d1\u3059\u3002\u56fd\u571f\u4ea4\u901a\u7701\u306b\u3088\u308b\u3068\u3001\uff11\uff17\u65e5\u6642\u70b9\u3067\u7d04\uff12\uff11\u4e07\u4ef6\u306e\u4e8b\u524d\u767b\u9332\u304c\u3042\u3063\u305f\u3002(\u4e00\u90e8\u65b0\u805e\u5831\u9053\u304b\u3089\u5f15\u7528)<br>\u624b\u6301\u3061\u306e\u6a5f\u4f53\u306f\u767b\u9332\u624b\u7d9a\u304d\u3092\u6e08\u307e\u305b\u3066,\u6a5f\u4f53\u306b\u30c6\u30d7\u30e9\u3067\u767b\u9332\u8a18\u53f7\u3092\u5f35\u308a\u4ed8\u3051\u305f\u3002\u3057\u3070\u3089\u304f\u306f\u30ea\u30e2\u30fc\u30c8ID\u5316\u5bfe\u5fdc\u306b\u3057\u306a\u304f\u3066\u3082\u5927\u4e08\u592b\u305d\u3046\u3060\u304c,\u3044\u305a\u308c\u30ea\u30e2\u30fc\u30c8ID\u5316\u304c\u5fc5\u8981\u3068\u306a\u308a\u305d\u3046\u3060\u3002<br>DJI\u3067\u306f\u4e00\u90e8\u6a5f\u4f53\u306b\u95a2\u3057\u3066\u306f,\u30d5\u30a1\u30fc\u30e0\u30a6\u30a7\u30a2\u306e\u66f4\u65b0\u3067\u5bfe\u5fdc\u3067\u304d\u308b\u3088\u3046\u3060\u3002\u624b\u6301\u3061\u306e\u6a5f\u4f53\u3067\u306fMAVIC AIR2\u304c\u30d5\u30a1\u30fc\u30e0\u30a6\u30a7\u30a2\u306e\u66f4\u65b0\u3067\u4eca\u5f8c\u30ea\u30e2\u30fc\u30c8ID\u5bfe\u5fdc\u3055\u308c\u308b\u305d\u3046\u3060\u3002<br>\u98db\u884c\u8a31\u53ef\u30fb\u627f\u8a8d\u306b\u3064\u3044\u3066,\u5168\u3066\u53d6\u308a\u76f4\u3057\u3066\u767b\u9332\u8a18\u53f7\u304c<a href=\"https:\/\/na-3.com\/wp_na-blog\/%e3%83%89%e3%83%ad%e3%83%bc%e3%83%b3\/%e7%84%a1%e4%ba%ba%e8%88%aa%e7%a9%ba%e6%a9%9f%e9%a3%9b%e8%a1%8c%e8%a8%b1%e5%8f%af%e3%83%bb%e6%89%bf%e8%aa%8d%e6%9b%b8\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u8a31\u53ef\u30fb\u627f\u8a8d\u66f8<\/a>\u306b\u8a18\u8f09\u3055\u308c\u305f\u3002<\/p>\n\n\n\n<p class=\"has-cyan-bluish-gray-background-color has-background wp-block-paragraph\">\u3010<a rel=\"noreferrer noopener\" href=\"https:\/\/www.dji.com\/jp\/flysafe?site=brandsite&amp;from=nav\" target=\"_blank\">DJI\u306e\u30a2\u30ca\u30a6\u30f3\u30b9<\/a>\u3011<br>\u30c9\u30ed\u30fc\u30f3\u306e\u767b\u9332\u7fa9\u52d9\u5316\u306b\u4f34\u3046\u30ea\u30e2\u30fc\u30c8 ID \u5bfe\u5fdc\u6a5f\u7a2e\u306b\u3064\u3044\u3066<br>2022\u5e74 6 \u6708 20 \u65e5\u3088\u308a\u958b\u59cb\u3055\u308c\u308b\u7121\u4eba\u822a\u7a7a\u6a5f\u306e\u767b\u9332\u7fa9\u52d9\u5316\u306b\u4f34\u3044\u3001\u65e5\u672c\u56fd\u5185\u5411\u3051\u306b\u8ca9\u58f2\u3057\u3066\u3044\u308b\u4e00\u90e8\u6a5f\u7a2e\u306b\u95a2\u3057\u3001\u4eca\u5f8c\u306e\u30d5\u30a1\u30fc\u30e0\u30a6\u30a7\u30a2\u66f4\u65b0\u3067\u5185\u8535\u30ea\u30e2\u30fc\u30c8 ID \u6a5f\u80fd\u5bfe\u5fdc\u3092\u4e88\u5b9a\u3057\u3066\u3044\u307e\u3059\u3002<br>\u5bfe\u5fdc\u4e88\u5b9a\u6a5f\u7a2e\uff1a DJI Mini 3 Pro\/DJI Mavic 3 \u30b7\u30ea\u30fc\u30ba\/DJI Air 2S\/Mavic Air 2 \/DJI Mini 2\/DJI FPV \/Matrice 30\u30b7\u30ea\u30fc\u30ba\/Matrice 300 RTK\/ AGRAS T30\/AGRAS T10 \u3002<br>\u5bfe\u5fdc\u6642\u671f\uff1a 2022\u5e746\u670820\u65e5\u4ee5\u964d\u3001\u9806\u6b21\u5bfe\u5fdc\u3057\u3066\u3044\u304f\u4e88\u5b9a\u3067\u3059\u3002<br>\u4eca\u5f8c\u3001<a href=\"https:\/\/www.dji.com\/jp\/newsroom?site=brandsite&amp;from=nav\" target=\"_blank\" rel=\"noreferrer noopener\">DJI \u30cb\u30e5\u30fc\u30b9\u30eb\u30fc\u30e0<\/a>\u3092\u3054\u78ba\u8a8d\u304f\u3060\u3055\u3044\u3002<br>\u4e0a\u8a18\u4ee5\u5916\u306e\u6a5f\u7a2e\u306f\u3001\u30ea\u30e2\u30fc\u30c8ID\u6a5f\u80fd\u306e\u5bfe\u5fdc\u3092\u4e88\u5b9a\u3057\u3066\u3044\u307e\u305b\u3093\u3002<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u6b8b\u308b\u306f\u4eca\u5e74\u306e12\u6708\u304b\u3089\u65bd\u884c\u958b\u59cb\u4e88\u5b9a\u306e\u56fd\u5bb6\u30e9\u30a4\u30bb\u30f3\u30b9\u5236\u5ea6\u3060\u3002\u56fd\u5bb6\u30e9\u30a4\u30bb\u30f3\u30b9\u3092\u53d6\u5f97\u3059\u308c\u3070,\u4e00\u90e8\u306e\u98db\u884c\u304c\u8a31\u53ef\u30fb\u627f\u8a8d\u4e0d\u8981\u3068\u306a\u308b\u3002\u901a\u5e38\u306e\u98db\u884c\u306b\u4fc2\u308b\u8a31\u53ef\u30fb\u627f\u8a8d\u304c\u4e0d\u8981\u3068\u306a\u308b\u306e\u306f\u3042\u308a\u304c\u305f\u3044\u3002<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.dji.com\/jp\/newsroom\/news\/dji-remoteid\" target=\"_blank\" rel=\"noopener\">\u7121\u4eba\u822a\u7a7a\u6a5f \u767b\u9332\u7fa9\u52d9\u5316\u306b\u4f34\u3046\u30ea\u30e2\u30fc\u30c8ID\u5bfe\u5fdc\u6a5f\u7a2e\u306b\u95a2\u3059\u308b\u304a\u77e5\u3089\u305b \u2013 DJI<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/store.dji.com\/jp\/guides\/drone-law\/\" target=\"_blank\" rel=\"noopener\">\u3010\u89e3\u8aac\u3011\u30ea\u30e2\u30fc\u30c8ID\u5bfe\u5fdc\u6a5f\u7a2e\u306b\u5bfe\u3059\u308b\u30ea\u30e2\u30fc\u30c8ID\u66f8\u8fbc\u307f\u65b9\u6cd5 \u2013 \u4e00\u822c\u5411\u3051\u30c9\u30ed\u30fc\u30f3 \u2013 DJI BUYING GUIDES<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u30c9\u30ed\u30fc\u30f3\u306e\u6a5f\u4f53\u767b\u9332\u7fa9\u52d9\u5236\u5ea6\u304c\u672c\u65e5\uff12\uff10\u65e5\u304b\u3089\u59cb\u307e\u3063\u305f\u3002\uff11\uff10\uff10\u30b0 <a class=\"more-link\" href=\"https:\/\/na-3.com\/wp_na-blog\/2022\/06\/20\/%e3%83%89%e3%83%ad%e3%83%bc%e3%83%b3%e3%81%ae%e6%a9%9f%e4%bd%93%e7%99%bb%e9%8c%b2%e7%be%a9%e5%8b%99%e9%96%8b%e5%a7%8b\/\">\u7d9a\u304d\u3092\u8aad\u3080 &rarr;<\/a><\/p>\n","protected":false},"author":1,"featured_media":4352,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0,"footnotes":""},"categories":[41,112],"tags":[357,358],"class_list":["post-7076","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-drone","category-permission-to-fly","tag-id","tag-358"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"\u30c9\u30ed\u30fc\u30f3\u306e\u6a5f\u4f53\u767b\u9332\u7fa9\u52d9\u5236\u5ea6\u304c\u672c\u65e5\uff12\uff10\u65e5\u304b\u3089\u59cb\u307e\u3063\u305f\u3002\uff11\uff10\uff10\u30b0\u30e9\u30e0\u4ee5\u4e0a\u304c\u5bfe\u8c61\u3067MAVIC MINI\u3082\u5bfe\u8c61\u3068\u306a\u308b\u3002\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"na-3\"\/>\n\t<meta name=\"google-site-verification\" content=\"BOtCJ-tDpXzYuHDLP-2mdI9BxtfrXGE0m0Q0KGx270k\" \/>\n\t<meta name=\"msvalidate.01\" content=\"bdf0193975b24ea888aa1fd6bdecdc66\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/na-3.com\/wp_na-blog\/2022\/06\/20\/%e3%83%89%e3%83%ad%e3%83%bc%e3%83%b3%e3%81%ae%e6%a9%9f%e4%bd%93%e7%99%bb%e9%8c%b2%e7%be%a9%e5%8b%99%e9%96%8b%e5%a7%8b\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"ja_JP\" \/>\n\t\t<meta property=\"og:site_name\" content=\"na-blog - \u52dd\u624b\u6c17\u307e\u307e\u306a\u72ec\u308a\u8a00\u306e\u30d6\u30ed\u30b0\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"\u30c9\u30ed\u30fc\u30f3\u306e\u6a5f\u4f53\u767b\u9332\u7fa9\u52d9\u958b\u59cb - na-blog\" \/>\n\t\t<meta property=\"og:description\" content=\"\u30c9\u30ed\u30fc\u30f3\u306e\u6a5f\u4f53\u767b\u9332\u7fa9\u52d9\u5236\u5ea6\u304c\u672c\u65e5\uff12\uff10\u65e5\u304b\u3089\u59cb\u307e\u3063\u305f\u3002\uff11\uff10\uff10\u30b0\u30e9\u30e0\u4ee5\u4e0a\u304c\u5bfe\u8c61\u3067MAVIC MINI\u3082\u5bfe\u8c61\u3068\u306a\u308b\u3002\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/na-3.com\/wp_na-blog\/2022\/06\/20\/%e3%83%89%e3%83%ad%e3%83%bc%e3%83%b3%e3%81%ae%e6%a9%9f%e4%bd%93%e7%99%bb%e9%8c%b2%e7%be%a9%e5%8b%99%e9%96%8b%e5%a7%8b\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/na-3.com\/wp_na-blog\/wp-content\/uploads\/2022\/05\/1DX24212_1t.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/na-3.com\/wp_na-blog\/wp-content\/uploads\/2022\/05\/1DX24212_1t.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2022-06-19T22:00:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2022-09-23T13:36:32+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"\u30c9\u30ed\u30fc\u30f3\u306e\u6a5f\u4f53\u767b\u9332\u7fa9\u52d9\u958b\u59cb - na-blog\" \/>\n\t\t<meta name=\"twitter:description\" content=\"\u30c9\u30ed\u30fc\u30f3\u306e\u6a5f\u4f53\u767b\u9332\u7fa9\u52d9\u5236\u5ea6\u304c\u672c\u65e5\uff12\uff10\u65e5\u304b\u3089\u59cb\u307e\u3063\u305f\u3002\uff11\uff10\uff10\u30b0\u30e9\u30e0\u4ee5\u4e0a\u304c\u5bfe\u8c61\u3067MAVIC MINI\u3082\u5bfe\u8c61\u3068\u306a\u308b\u3002\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/na-3.com\/wp_na-blog\/wp-content\/uploads\/2022\/05\/1DX24212_1t.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/na-3.com\\\/wp_na-blog\\\/2022\\\/06\\\/20\\\/%e3%83%89%e3%83%ad%e3%83%bc%e3%83%b3%e3%81%ae%e6%a9%9f%e4%bd%93%e7%99%bb%e9%8c%b2%e7%be%a9%e5%8b%99%e9%96%8b%e5%a7%8b\\\/#blogposting\",\"name\":\"\\u30c9\\u30ed\\u30fc\\u30f3\\u306e\\u6a5f\\u4f53\\u767b\\u9332\\u7fa9\\u52d9\\u958b\\u59cb - na-blog\",\"headline\":\"\\u30c9\\u30ed\\u30fc\\u30f3\\u306e\\u6a5f\\u4f53\\u767b\\u9332\\u7fa9\\u52d9\\u958b\\u59cb\",\"author\":{\"@id\":\"https:\\\/\\\/na-3.com\\\/wp_na-blog\\\/author\\\/na-3\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/na-3.com\\\/wp_na-blog\\\/#person\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/na-3.com\\\/wp_na-blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/\\u30c9\\u30ed\\u30fc\\u30f3\\u30d5\\u30a1\\u30df\\u30ea\\u30fc.jpg\",\"width\":1024,\"height\":576},\"datePublished\":\"2022-06-20T07:00:00+09:00\",\"dateModified\":\"2022-09-23T22:36:32+09:00\",\"inLanguage\":\"ja\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/na-3.com\\\/wp_na-blog\\\/2022\\\/06\\\/20\\\/%e3%83%89%e3%83%ad%e3%83%bc%e3%83%b3%e3%81%ae%e6%a9%9f%e4%bd%93%e7%99%bb%e9%8c%b2%e7%be%a9%e5%8b%99%e9%96%8b%e5%a7%8b\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/na-3.com\\\/wp_na-blog\\\/2022\\\/06\\\/20\\\/%e3%83%89%e3%83%ad%e3%83%bc%e3%83%b3%e3%81%ae%e6%a9%9f%e4%bd%93%e7%99%bb%e9%8c%b2%e7%be%a9%e5%8b%99%e9%96%8b%e5%a7%8b\\\/#webpage\"},\"articleSection\":\"\\u30c9\\u30ed\\u30fc\\u30f3, \\u98db\\u884c\\u8a31\\u53ef, \\u30ea\\u30e2\\u30fc\\u30c8ID, \\u767b\\u9332\\u7fa9\\u52d9\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/na-3.com\\\/wp_na-blog\\\/2022\\\/06\\\/20\\\/%e3%83%89%e3%83%ad%e3%83%bc%e3%83%b3%e3%81%ae%e6%a9%9f%e4%bd%93%e7%99%bb%e9%8c%b2%e7%be%a9%e5%8b%99%e9%96%8b%e5%a7%8b\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/na-3.com\\\/wp_na-blog#listItem\",\"position\":1,\"name\":\"\\u30db\\u30fc\\u30e0\",\"item\":\"https:\\\/\\\/na-3.com\\\/wp_na-blog\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/na-3.com\\\/wp_na-blog\\\/category\\\/photograph\\\/#listItem\",\"name\":\"\\u5199\\u771f\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/na-3.com\\\/wp_na-blog\\\/category\\\/photograph\\\/#listItem\",\"position\":2,\"name\":\"\\u5199\\u771f\",\"item\":\"https:\\\/\\\/na-3.com\\\/wp_na-blog\\\/category\\\/photograph\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/na-3.com\\\/wp_na-blog\\\/category\\\/photograph\\\/photographic-equipment\\\/#listItem\",\"name\":\"\\u64ae\\u5f71\\u6a5f\\u6750\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/na-3.com\\\/wp_na-blog#listItem\",\"name\":\"\\u30db\\u30fc\\u30e0\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/na-3.com\\\/wp_na-blog\\\/category\\\/photograph\\\/photographic-equipment\\\/#listItem\",\"position\":3,\"name\":\"\\u64ae\\u5f71\\u6a5f\\u6750\",\"item\":\"https:\\\/\\\/na-3.com\\\/wp_na-blog\\\/category\\\/photograph\\\/photographic-equipment\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/na-3.com\\\/wp_na-blog\\\/category\\\/photograph\\\/photographic-equipment\\\/drone\\\/#listItem\",\"name\":\"\\u30c9\\u30ed\\u30fc\\u30f3\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/na-3.com\\\/wp_na-blog\\\/category\\\/photograph\\\/#listItem\",\"name\":\"\\u5199\\u771f\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/na-3.com\\\/wp_na-blog\\\/category\\\/photograph\\\/photographic-equipment\\\/drone\\\/#listItem\",\"position\":4,\"name\":\"\\u30c9\\u30ed\\u30fc\\u30f3\",\"item\":\"https:\\\/\\\/na-3.com\\\/wp_na-blog\\\/category\\\/photograph\\\/photographic-equipment\\\/drone\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/na-3.com\\\/wp_na-blog\\\/category\\\/photograph\\\/photographic-equipment\\\/drone\\\/permission-to-fly\\\/#listItem\",\"name\":\"\\u98db\\u884c\\u8a31\\u53ef\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/na-3.com\\\/wp_na-blog\\\/category\\\/photograph\\\/photographic-equipment\\\/#listItem\",\"name\":\"\\u64ae\\u5f71\\u6a5f\\u6750\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/na-3.com\\\/wp_na-blog\\\/category\\\/photograph\\\/photographic-equipment\\\/drone\\\/permission-to-fly\\\/#listItem\",\"position\":5,\"name\":\"\\u98db\\u884c\\u8a31\\u53ef\",\"item\":\"https:\\\/\\\/na-3.com\\\/wp_na-blog\\\/category\\\/photograph\\\/photographic-equipment\\\/drone\\\/permission-to-fly\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/na-3.com\\\/wp_na-blog\\\/2022\\\/06\\\/20\\\/%e3%83%89%e3%83%ad%e3%83%bc%e3%83%b3%e3%81%ae%e6%a9%9f%e4%bd%93%e7%99%bb%e9%8c%b2%e7%be%a9%e5%8b%99%e9%96%8b%e5%a7%8b\\\/#listItem\",\"name\":\"\\u30c9\\u30ed\\u30fc\\u30f3\\u306e\\u6a5f\\u4f53\\u767b\\u9332\\u7fa9\\u52d9\\u958b\\u59cb\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/na-3.com\\\/wp_na-blog\\\/category\\\/photograph\\\/photographic-equipment\\\/drone\\\/#listItem\",\"name\":\"\\u30c9\\u30ed\\u30fc\\u30f3\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/na-3.com\\\/wp_na-blog\\\/2022\\\/06\\\/20\\\/%e3%83%89%e3%83%ad%e3%83%bc%e3%83%b3%e3%81%ae%e6%a9%9f%e4%bd%93%e7%99%bb%e9%8c%b2%e7%be%a9%e5%8b%99%e9%96%8b%e5%a7%8b\\\/#listItem\",\"position\":6,\"name\":\"\\u30c9\\u30ed\\u30fc\\u30f3\\u306e\\u6a5f\\u4f53\\u767b\\u9332\\u7fa9\\u52d9\\u958b\\u59cb\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/na-3.com\\\/wp_na-blog\\\/category\\\/photograph\\\/photographic-equipment\\\/drone\\\/permission-to-fly\\\/#listItem\",\"name\":\"\\u98db\\u884c\\u8a31\\u53ef\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/na-3.com\\\/wp_na-blog\\\/#person\",\"name\":\"na-3\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/na-3.com\\\/wp_na-blog\\\/2022\\\/06\\\/20\\\/%e3%83%89%e3%83%ad%e3%83%bc%e3%83%b3%e3%81%ae%e6%a9%9f%e4%bd%93%e7%99%bb%e9%8c%b2%e7%be%a9%e5%8b%99%e9%96%8b%e5%a7%8b\\\/#personImage\",\"url\":\"https:\\\/\\\/na-3.com\\\/wp_na-blog\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/1DX24212_1t-150x150.jpg\",\"width\":96,\"height\":96,\"caption\":\"na-3\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/na-3.com\\\/wp_na-blog\\\/author\\\/na-3\\\/#author\",\"url\":\"https:\\\/\\\/na-3.com\\\/wp_na-blog\\\/author\\\/na-3\\\/\",\"name\":\"na-3\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/na-3.com\\\/wp_na-blog\\\/2022\\\/06\\\/20\\\/%e3%83%89%e3%83%ad%e3%83%bc%e3%83%b3%e3%81%ae%e6%a9%9f%e4%bd%93%e7%99%bb%e9%8c%b2%e7%be%a9%e5%8b%99%e9%96%8b%e5%a7%8b\\\/#authorImage\",\"url\":\"https:\\\/\\\/na-3.com\\\/wp_na-blog\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/1DX24212_1t-150x150.jpg\",\"width\":96,\"height\":96,\"caption\":\"na-3\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/na-3.com\\\/wp_na-blog\\\/2022\\\/06\\\/20\\\/%e3%83%89%e3%83%ad%e3%83%bc%e3%83%b3%e3%81%ae%e6%a9%9f%e4%bd%93%e7%99%bb%e9%8c%b2%e7%be%a9%e5%8b%99%e9%96%8b%e5%a7%8b\\\/#webpage\",\"url\":\"https:\\\/\\\/na-3.com\\\/wp_na-blog\\\/2022\\\/06\\\/20\\\/%e3%83%89%e3%83%ad%e3%83%bc%e3%83%b3%e3%81%ae%e6%a9%9f%e4%bd%93%e7%99%bb%e9%8c%b2%e7%be%a9%e5%8b%99%e9%96%8b%e5%a7%8b\\\/\",\"name\":\"\\u30c9\\u30ed\\u30fc\\u30f3\\u306e\\u6a5f\\u4f53\\u767b\\u9332\\u7fa9\\u52d9\\u958b\\u59cb - na-blog\",\"description\":\"\\u30c9\\u30ed\\u30fc\\u30f3\\u306e\\u6a5f\\u4f53\\u767b\\u9332\\u7fa9\\u52d9\\u5236\\u5ea6\\u304c\\u672c\\u65e5\\uff12\\uff10\\u65e5\\u304b\\u3089\\u59cb\\u307e\\u3063\\u305f\\u3002\\uff11\\uff10\\uff10\\u30b0\\u30e9\\u30e0\\u4ee5\\u4e0a\\u304c\\u5bfe\\u8c61\\u3067MAVIC MINI\\u3082\\u5bfe\\u8c61\\u3068\\u306a\\u308b\\u3002\",\"inLanguage\":\"ja\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/na-3.com\\\/wp_na-blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/na-3.com\\\/wp_na-blog\\\/2022\\\/06\\\/20\\\/%e3%83%89%e3%83%ad%e3%83%bc%e3%83%b3%e3%81%ae%e6%a9%9f%e4%bd%93%e7%99%bb%e9%8c%b2%e7%be%a9%e5%8b%99%e9%96%8b%e5%a7%8b\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/na-3.com\\\/wp_na-blog\\\/author\\\/na-3\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/na-3.com\\\/wp_na-blog\\\/author\\\/na-3\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/na-3.com\\\/wp_na-blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/\\u30c9\\u30ed\\u30fc\\u30f3\\u30d5\\u30a1\\u30df\\u30ea\\u30fc.jpg\",\"@id\":\"https:\\\/\\\/na-3.com\\\/wp_na-blog\\\/2022\\\/06\\\/20\\\/%e3%83%89%e3%83%ad%e3%83%bc%e3%83%b3%e3%81%ae%e6%a9%9f%e4%bd%93%e7%99%bb%e9%8c%b2%e7%be%a9%e5%8b%99%e9%96%8b%e5%a7%8b\\\/#mainImage\",\"width\":1024,\"height\":576},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/na-3.com\\\/wp_na-blog\\\/2022\\\/06\\\/20\\\/%e3%83%89%e3%83%ad%e3%83%bc%e3%83%b3%e3%81%ae%e6%a9%9f%e4%bd%93%e7%99%bb%e9%8c%b2%e7%be%a9%e5%8b%99%e9%96%8b%e5%a7%8b\\\/#mainImage\"},\"datePublished\":\"2022-06-20T07:00:00+09:00\",\"dateModified\":\"2022-09-23T22:36:32+09:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/na-3.com\\\/wp_na-blog\\\/#website\",\"url\":\"https:\\\/\\\/na-3.com\\\/wp_na-blog\\\/\",\"name\":\"na-blog\",\"alternateName\":\"\\u306a\\u30fc\\u30d6\\u30ed\\u30b0\",\"description\":\"\\u52dd\\u624b\\u6c17\\u307e\\u307e\\u306a\\u72ec\\u308a\\u8a00\\u306e\\u30d6\\u30ed\\u30b0\",\"inLanguage\":\"ja\",\"publisher\":{\"@id\":\"https:\\\/\\\/na-3.com\\\/wp_na-blog\\\/#person\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"\u30c9\u30ed\u30fc\u30f3\u306e\u6a5f\u4f53\u767b\u9332\u7fa9\u52d9\u958b\u59cb - na-blog","description":"\u30c9\u30ed\u30fc\u30f3\u306e\u6a5f\u4f53\u767b\u9332\u7fa9\u52d9\u5236\u5ea6\u304c\u672c\u65e5\uff12\uff10\u65e5\u304b\u3089\u59cb\u307e\u3063\u305f\u3002\uff11\uff10\uff10\u30b0\u30e9\u30e0\u4ee5\u4e0a\u304c\u5bfe\u8c61\u3067MAVIC MINI\u3082\u5bfe\u8c61\u3068\u306a\u308b\u3002","canonical_url":"https:\/\/na-3.com\/wp_na-blog\/2022\/06\/20\/%e3%83%89%e3%83%ad%e3%83%bc%e3%83%b3%e3%81%ae%e6%a9%9f%e4%bd%93%e7%99%bb%e9%8c%b2%e7%be%a9%e5%8b%99%e9%96%8b%e5%a7%8b\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"BOtCJ-tDpXzYuHDLP-2mdI9BxtfrXGE0m0Q0KGx270k","msvalidate.01":"bdf0193975b24ea888aa1fd6bdecdc66","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/na-3.com\/wp_na-blog\/2022\/06\/20\/%e3%83%89%e3%83%ad%e3%83%bc%e3%83%b3%e3%81%ae%e6%a9%9f%e4%bd%93%e7%99%bb%e9%8c%b2%e7%be%a9%e5%8b%99%e9%96%8b%e5%a7%8b\/#blogposting","name":"\u30c9\u30ed\u30fc\u30f3\u306e\u6a5f\u4f53\u767b\u9332\u7fa9\u52d9\u958b\u59cb - na-blog","headline":"\u30c9\u30ed\u30fc\u30f3\u306e\u6a5f\u4f53\u767b\u9332\u7fa9\u52d9\u958b\u59cb","author":{"@id":"https:\/\/na-3.com\/wp_na-blog\/author\/na-3\/#author"},"publisher":{"@id":"https:\/\/na-3.com\/wp_na-blog\/#person"},"image":{"@type":"ImageObject","url":"https:\/\/na-3.com\/wp_na-blog\/wp-content\/uploads\/2021\/05\/\u30c9\u30ed\u30fc\u30f3\u30d5\u30a1\u30df\u30ea\u30fc.jpg","width":1024,"height":576},"datePublished":"2022-06-20T07:00:00+09:00","dateModified":"2022-09-23T22:36:32+09:00","inLanguage":"ja","mainEntityOfPage":{"@id":"https:\/\/na-3.com\/wp_na-blog\/2022\/06\/20\/%e3%83%89%e3%83%ad%e3%83%bc%e3%83%b3%e3%81%ae%e6%a9%9f%e4%bd%93%e7%99%bb%e9%8c%b2%e7%be%a9%e5%8b%99%e9%96%8b%e5%a7%8b\/#webpage"},"isPartOf":{"@id":"https:\/\/na-3.com\/wp_na-blog\/2022\/06\/20\/%e3%83%89%e3%83%ad%e3%83%bc%e3%83%b3%e3%81%ae%e6%a9%9f%e4%bd%93%e7%99%bb%e9%8c%b2%e7%be%a9%e5%8b%99%e9%96%8b%e5%a7%8b\/#webpage"},"articleSection":"\u30c9\u30ed\u30fc\u30f3, \u98db\u884c\u8a31\u53ef, \u30ea\u30e2\u30fc\u30c8ID, \u767b\u9332\u7fa9\u52d9"},{"@type":"BreadcrumbList","@id":"https:\/\/na-3.com\/wp_na-blog\/2022\/06\/20\/%e3%83%89%e3%83%ad%e3%83%bc%e3%83%b3%e3%81%ae%e6%a9%9f%e4%bd%93%e7%99%bb%e9%8c%b2%e7%be%a9%e5%8b%99%e9%96%8b%e5%a7%8b\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/na-3.com\/wp_na-blog#listItem","position":1,"name":"\u30db\u30fc\u30e0","item":"https:\/\/na-3.com\/wp_na-blog","nextItem":{"@type":"ListItem","@id":"https:\/\/na-3.com\/wp_na-blog\/category\/photograph\/#listItem","name":"\u5199\u771f"}},{"@type":"ListItem","@id":"https:\/\/na-3.com\/wp_na-blog\/category\/photograph\/#listItem","position":2,"name":"\u5199\u771f","item":"https:\/\/na-3.com\/wp_na-blog\/category\/photograph\/","nextItem":{"@type":"ListItem","@id":"https:\/\/na-3.com\/wp_na-blog\/category\/photograph\/photographic-equipment\/#listItem","name":"\u64ae\u5f71\u6a5f\u6750"},"previousItem":{"@type":"ListItem","@id":"https:\/\/na-3.com\/wp_na-blog#listItem","name":"\u30db\u30fc\u30e0"}},{"@type":"ListItem","@id":"https:\/\/na-3.com\/wp_na-blog\/category\/photograph\/photographic-equipment\/#listItem","position":3,"name":"\u64ae\u5f71\u6a5f\u6750","item":"https:\/\/na-3.com\/wp_na-blog\/category\/photograph\/photographic-equipment\/","nextItem":{"@type":"ListItem","@id":"https:\/\/na-3.com\/wp_na-blog\/category\/photograph\/photographic-equipment\/drone\/#listItem","name":"\u30c9\u30ed\u30fc\u30f3"},"previousItem":{"@type":"ListItem","@id":"https:\/\/na-3.com\/wp_na-blog\/category\/photograph\/#listItem","name":"\u5199\u771f"}},{"@type":"ListItem","@id":"https:\/\/na-3.com\/wp_na-blog\/category\/photograph\/photographic-equipment\/drone\/#listItem","position":4,"name":"\u30c9\u30ed\u30fc\u30f3","item":"https:\/\/na-3.com\/wp_na-blog\/category\/photograph\/photographic-equipment\/drone\/","nextItem":{"@type":"ListItem","@id":"https:\/\/na-3.com\/wp_na-blog\/category\/photograph\/photographic-equipment\/drone\/permission-to-fly\/#listItem","name":"\u98db\u884c\u8a31\u53ef"},"previousItem":{"@type":"ListItem","@id":"https:\/\/na-3.com\/wp_na-blog\/category\/photograph\/photographic-equipment\/#listItem","name":"\u64ae\u5f71\u6a5f\u6750"}},{"@type":"ListItem","@id":"https:\/\/na-3.com\/wp_na-blog\/category\/photograph\/photographic-equipment\/drone\/permission-to-fly\/#listItem","position":5,"name":"\u98db\u884c\u8a31\u53ef","item":"https:\/\/na-3.com\/wp_na-blog\/category\/photograph\/photographic-equipment\/drone\/permission-to-fly\/","nextItem":{"@type":"ListItem","@id":"https:\/\/na-3.com\/wp_na-blog\/2022\/06\/20\/%e3%83%89%e3%83%ad%e3%83%bc%e3%83%b3%e3%81%ae%e6%a9%9f%e4%bd%93%e7%99%bb%e9%8c%b2%e7%be%a9%e5%8b%99%e9%96%8b%e5%a7%8b\/#listItem","name":"\u30c9\u30ed\u30fc\u30f3\u306e\u6a5f\u4f53\u767b\u9332\u7fa9\u52d9\u958b\u59cb"},"previousItem":{"@type":"ListItem","@id":"https:\/\/na-3.com\/wp_na-blog\/category\/photograph\/photographic-equipment\/drone\/#listItem","name":"\u30c9\u30ed\u30fc\u30f3"}},{"@type":"ListItem","@id":"https:\/\/na-3.com\/wp_na-blog\/2022\/06\/20\/%e3%83%89%e3%83%ad%e3%83%bc%e3%83%b3%e3%81%ae%e6%a9%9f%e4%bd%93%e7%99%bb%e9%8c%b2%e7%be%a9%e5%8b%99%e9%96%8b%e5%a7%8b\/#listItem","position":6,"name":"\u30c9\u30ed\u30fc\u30f3\u306e\u6a5f\u4f53\u767b\u9332\u7fa9\u52d9\u958b\u59cb","previousItem":{"@type":"ListItem","@id":"https:\/\/na-3.com\/wp_na-blog\/category\/photograph\/photographic-equipment\/drone\/permission-to-fly\/#listItem","name":"\u98db\u884c\u8a31\u53ef"}}]},{"@type":"Person","@id":"https:\/\/na-3.com\/wp_na-blog\/#person","name":"na-3","image":{"@type":"ImageObject","@id":"https:\/\/na-3.com\/wp_na-blog\/2022\/06\/20\/%e3%83%89%e3%83%ad%e3%83%bc%e3%83%b3%e3%81%ae%e6%a9%9f%e4%bd%93%e7%99%bb%e9%8c%b2%e7%be%a9%e5%8b%99%e9%96%8b%e5%a7%8b\/#personImage","url":"https:\/\/na-3.com\/wp_na-blog\/wp-content\/uploads\/2022\/05\/1DX24212_1t-150x150.jpg","width":96,"height":96,"caption":"na-3"}},{"@type":"Person","@id":"https:\/\/na-3.com\/wp_na-blog\/author\/na-3\/#author","url":"https:\/\/na-3.com\/wp_na-blog\/author\/na-3\/","name":"na-3","image":{"@type":"ImageObject","@id":"https:\/\/na-3.com\/wp_na-blog\/2022\/06\/20\/%e3%83%89%e3%83%ad%e3%83%bc%e3%83%b3%e3%81%ae%e6%a9%9f%e4%bd%93%e7%99%bb%e9%8c%b2%e7%be%a9%e5%8b%99%e9%96%8b%e5%a7%8b\/#authorImage","url":"https:\/\/na-3.com\/wp_na-blog\/wp-content\/uploads\/2022\/05\/1DX24212_1t-150x150.jpg","width":96,"height":96,"caption":"na-3"}},{"@type":"WebPage","@id":"https:\/\/na-3.com\/wp_na-blog\/2022\/06\/20\/%e3%83%89%e3%83%ad%e3%83%bc%e3%83%b3%e3%81%ae%e6%a9%9f%e4%bd%93%e7%99%bb%e9%8c%b2%e7%be%a9%e5%8b%99%e9%96%8b%e5%a7%8b\/#webpage","url":"https:\/\/na-3.com\/wp_na-blog\/2022\/06\/20\/%e3%83%89%e3%83%ad%e3%83%bc%e3%83%b3%e3%81%ae%e6%a9%9f%e4%bd%93%e7%99%bb%e9%8c%b2%e7%be%a9%e5%8b%99%e9%96%8b%e5%a7%8b\/","name":"\u30c9\u30ed\u30fc\u30f3\u306e\u6a5f\u4f53\u767b\u9332\u7fa9\u52d9\u958b\u59cb - na-blog","description":"\u30c9\u30ed\u30fc\u30f3\u306e\u6a5f\u4f53\u767b\u9332\u7fa9\u52d9\u5236\u5ea6\u304c\u672c\u65e5\uff12\uff10\u65e5\u304b\u3089\u59cb\u307e\u3063\u305f\u3002\uff11\uff10\uff10\u30b0\u30e9\u30e0\u4ee5\u4e0a\u304c\u5bfe\u8c61\u3067MAVIC MINI\u3082\u5bfe\u8c61\u3068\u306a\u308b\u3002","inLanguage":"ja","isPartOf":{"@id":"https:\/\/na-3.com\/wp_na-blog\/#website"},"breadcrumb":{"@id":"https:\/\/na-3.com\/wp_na-blog\/2022\/06\/20\/%e3%83%89%e3%83%ad%e3%83%bc%e3%83%b3%e3%81%ae%e6%a9%9f%e4%bd%93%e7%99%bb%e9%8c%b2%e7%be%a9%e5%8b%99%e9%96%8b%e5%a7%8b\/#breadcrumblist"},"author":{"@id":"https:\/\/na-3.com\/wp_na-blog\/author\/na-3\/#author"},"creator":{"@id":"https:\/\/na-3.com\/wp_na-blog\/author\/na-3\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/na-3.com\/wp_na-blog\/wp-content\/uploads\/2021\/05\/\u30c9\u30ed\u30fc\u30f3\u30d5\u30a1\u30df\u30ea\u30fc.jpg","@id":"https:\/\/na-3.com\/wp_na-blog\/2022\/06\/20\/%e3%83%89%e3%83%ad%e3%83%bc%e3%83%b3%e3%81%ae%e6%a9%9f%e4%bd%93%e7%99%bb%e9%8c%b2%e7%be%a9%e5%8b%99%e9%96%8b%e5%a7%8b\/#mainImage","width":1024,"height":576},"primaryImageOfPage":{"@id":"https:\/\/na-3.com\/wp_na-blog\/2022\/06\/20\/%e3%83%89%e3%83%ad%e3%83%bc%e3%83%b3%e3%81%ae%e6%a9%9f%e4%bd%93%e7%99%bb%e9%8c%b2%e7%be%a9%e5%8b%99%e9%96%8b%e5%a7%8b\/#mainImage"},"datePublished":"2022-06-20T07:00:00+09:00","dateModified":"2022-09-23T22:36:32+09:00"},{"@type":"WebSite","@id":"https:\/\/na-3.com\/wp_na-blog\/#website","url":"https:\/\/na-3.com\/wp_na-blog\/","name":"na-blog","alternateName":"\u306a\u30fc\u30d6\u30ed\u30b0","description":"\u52dd\u624b\u6c17\u307e\u307e\u306a\u72ec\u308a\u8a00\u306e\u30d6\u30ed\u30b0","inLanguage":"ja","publisher":{"@id":"https:\/\/na-3.com\/wp_na-blog\/#person"}}]},"og:locale":"ja_JP","og:site_name":"na-blog - \u52dd\u624b\u6c17\u307e\u307e\u306a\u72ec\u308a\u8a00\u306e\u30d6\u30ed\u30b0","og:type":"article","og:title":"\u30c9\u30ed\u30fc\u30f3\u306e\u6a5f\u4f53\u767b\u9332\u7fa9\u52d9\u958b\u59cb - na-blog","og:description":"\u30c9\u30ed\u30fc\u30f3\u306e\u6a5f\u4f53\u767b\u9332\u7fa9\u52d9\u5236\u5ea6\u304c\u672c\u65e5\uff12\uff10\u65e5\u304b\u3089\u59cb\u307e\u3063\u305f\u3002\uff11\uff10\uff10\u30b0\u30e9\u30e0\u4ee5\u4e0a\u304c\u5bfe\u8c61\u3067MAVIC MINI\u3082\u5bfe\u8c61\u3068\u306a\u308b\u3002","og:url":"https:\/\/na-3.com\/wp_na-blog\/2022\/06\/20\/%e3%83%89%e3%83%ad%e3%83%bc%e3%83%b3%e3%81%ae%e6%a9%9f%e4%bd%93%e7%99%bb%e9%8c%b2%e7%be%a9%e5%8b%99%e9%96%8b%e5%a7%8b\/","og:image":"https:\/\/na-3.com\/wp_na-blog\/wp-content\/uploads\/2022\/05\/1DX24212_1t.jpg","og:image:secure_url":"https:\/\/na-3.com\/wp_na-blog\/wp-content\/uploads\/2022\/05\/1DX24212_1t.jpg","og:image:width":800,"og:image:height":800,"article:published_time":"2022-06-19T22:00:00+00:00","article:modified_time":"2022-09-23T13:36:32+00:00","twitter:card":"summary_large_image","twitter:title":"\u30c9\u30ed\u30fc\u30f3\u306e\u6a5f\u4f53\u767b\u9332\u7fa9\u52d9\u958b\u59cb - na-blog","twitter:description":"\u30c9\u30ed\u30fc\u30f3\u306e\u6a5f\u4f53\u767b\u9332\u7fa9\u52d9\u5236\u5ea6\u304c\u672c\u65e5\uff12\uff10\u65e5\u304b\u3089\u59cb\u307e\u3063\u305f\u3002\uff11\uff10\uff10\u30b0\u30e9\u30e0\u4ee5\u4e0a\u304c\u5bfe\u8c61\u3067MAVIC MINI\u3082\u5bfe\u8c61\u3068\u306a\u308b\u3002","twitter:image":"https:\/\/na-3.com\/wp_na-blog\/wp-content\/uploads\/2022\/05\/1DX24212_1t.jpg"},"aioseo_meta_data":{"post_id":"7076","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":false},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2022-07-25 05:39:09","updated":"2025-06-09 03:32:35","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/na-3.com\/wp_na-blog\" title=\"\u30db\u30fc\u30e0\">\u30db\u30fc\u30e0<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/na-3.com\/wp_na-blog\/category\/photograph\/\" title=\"\u5199\u771f\">\u5199\u771f<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/na-3.com\/wp_na-blog\/category\/photograph\/photographic-equipment\/\" title=\"\u64ae\u5f71\u6a5f\u6750\">\u64ae\u5f71\u6a5f\u6750<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/na-3.com\/wp_na-blog\/category\/photograph\/photographic-equipment\/drone\/\" title=\"\u30c9\u30ed\u30fc\u30f3\">\u30c9\u30ed\u30fc\u30f3<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/na-3.com\/wp_na-blog\/category\/photograph\/photographic-equipment\/drone\/permission-to-fly\/\" title=\"\u98db\u884c\u8a31\u53ef\">\u98db\u884c\u8a31\u53ef<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t\u30c9\u30ed\u30fc\u30f3\u306e\u6a5f\u4f53\u767b\u9332\u7fa9\u52d9\u958b\u59cb\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"\u30db\u30fc\u30e0","link":"https:\/\/na-3.com\/wp_na-blog"},{"label":"\u5199\u771f","link":"https:\/\/na-3.com\/wp_na-blog\/category\/photograph\/"},{"label":"\u64ae\u5f71\u6a5f\u6750","link":"https:\/\/na-3.com\/wp_na-blog\/category\/photograph\/photographic-equipment\/"},{"label":"\u30c9\u30ed\u30fc\u30f3","link":"https:\/\/na-3.com\/wp_na-blog\/category\/photograph\/photographic-equipment\/drone\/"},{"label":"\u98db\u884c\u8a31\u53ef","link":"https:\/\/na-3.com\/wp_na-blog\/category\/photograph\/photographic-equipment\/drone\/permission-to-fly\/"},{"label":"\u30c9\u30ed\u30fc\u30f3\u306e\u6a5f\u4f53\u767b\u9332\u7fa9\u52d9\u958b\u59cb","link":"https:\/\/na-3.com\/wp_na-blog\/2022\/06\/20\/%e3%83%89%e3%83%ad%e3%83%bc%e3%83%b3%e3%81%ae%e6%a9%9f%e4%bd%93%e7%99%bb%e9%8c%b2%e7%be%a9%e5%8b%99%e9%96%8b%e5%a7%8b\/"}],"_links":{"self":[{"href":"https:\/\/na-3.com\/wp_na-blog\/wp-json\/wp\/v2\/posts\/7076","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/na-3.com\/wp_na-blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/na-3.com\/wp_na-blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/na-3.com\/wp_na-blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/na-3.com\/wp_na-blog\/wp-json\/wp\/v2\/comments?post=7076"}],"version-history":[{"count":10,"href":"https:\/\/na-3.com\/wp_na-blog\/wp-json\/wp\/v2\/posts\/7076\/revisions"}],"predecessor-version":[{"id":7382,"href":"https:\/\/na-3.com\/wp_na-blog\/wp-json\/wp\/v2\/posts\/7076\/revisions\/7382"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/na-3.com\/wp_na-blog\/wp-json\/wp\/v2\/media\/4352"}],"wp:attachment":[{"href":"https:\/\/na-3.com\/wp_na-blog\/wp-json\/wp\/v2\/media?parent=7076"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/na-3.com\/wp_na-blog\/wp-json\/wp\/v2\/categories?post=7076"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/na-3.com\/wp_na-blog\/wp-json\/wp\/v2\/tags?post=7076"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}